{"id":8,"count":1,"description":"","link":"https:\/\/themes.dxdemos.eu\/hayley\/category\/buying\/","name":"buying","slug":"buying","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/themes.dxdemos.eu\/hayley\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themes.dxdemos.eu\/hayley\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/themes.dxdemos.eu\/hayley\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/themes.dxdemos.eu\/hayley\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}